{"id":871,"count":1,"description":"","link":"https:\/\/socialpubli.com\/blog\/tag\/innovation\/","name":"innovation","slug":"innovation","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>innovation Social Publi Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/socialpubli.com\/blog\/tag\/innovation\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"innovation Social Publi Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/socialpubli.com\/blog\/tag\/innovation\/\" \/>\n<meta property=\"og:site_name\" content=\"Social Publi Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/tag\\\/innovation\\\/\",\"url\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/tag\\\/innovation\\\/\",\"name\":\"innovation Social Publi Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/tag\\\/innovation\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/tag\\\/innovation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"innovation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/\",\"name\":\"Social Publi Blog\",\"description\":\"Tendencias en marketing de influencers, branded content y estrategia en redes sociales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/#organization\",\"name\":\"SocialPubli\",\"url\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/logo-blog.png\",\"contentUrl\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/logo-blog.png\",\"width\":284,\"height\":53,\"caption\":\"SocialPubli\"},\"image\":{\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"innovation Social Publi Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/socialpubli.com\/blog\/tag\/innovation\/","og_locale":"en_US","og_type":"article","og_title":"innovation Social Publi Blog","og_url":"https:\/\/socialpubli.com\/blog\/tag\/innovation\/","og_site_name":"Social Publi Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/socialpubli.com\/blog\/tag\/innovation\/","url":"https:\/\/socialpubli.com\/blog\/tag\/innovation\/","name":"innovation Social Publi Blog","isPartOf":{"@id":"https:\/\/socialpubli.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/socialpubli.com\/blog\/tag\/innovation\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/socialpubli.com\/blog\/tag\/innovation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/socialpubli.com\/blog\/"},{"@type":"ListItem","position":2,"name":"innovation"}]},{"@type":"WebSite","@id":"https:\/\/socialpubli.com\/blog\/#website","url":"https:\/\/socialpubli.com\/blog\/","name":"Social Publi Blog","description":"Tendencias en marketing de influencers, branded content y estrategia en redes sociales.","publisher":{"@id":"https:\/\/socialpubli.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/socialpubli.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/socialpubli.com\/blog\/#organization","name":"SocialPubli","url":"https:\/\/socialpubli.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/socialpubli.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2017\/01\/logo-blog.png","contentUrl":"https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2017\/01\/logo-blog.png","width":284,"height":53,"caption":"SocialPubli"},"image":{"@id":"https:\/\/socialpubli.com\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/socialpubli.com\/blog\/wp-json\/wp\/v2\/tags\/871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/socialpubli.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/socialpubli.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/socialpubli.com\/blog\/wp-json\/wp\/v2\/posts?tags=871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}