{"id":5281,"date":"2019-01-22T10:16:14","date_gmt":"2019-01-22T08:16:14","guid":{"rendered":"https:\/\/socialpubli.com\/news\/?p=5281"},"modified":"2019-01-16T18:22:19","modified_gmt":"2019-01-16T16:22:19","slug":"por-que-no-puedo-compartir-historias-instagram","status":"publish","type":"post","link":"https:\/\/socialpubli.com\/blog\/es\/por-que-no-puedo-compartir-historias-instagram\/","title":{"rendered":"\u00bfPor qu\u00e9 no puedo compartir historias de Instagram?"},"content":{"rendered":"<p>\u00abNo puedo compartir stories\u00bb. Es una de las frases m\u00e1s tr\u00e1gicas de este a\u00f1o, y acecha a grupos de amigos de todo el mundo. Pero no hay que preocuparse, porque con este post vamos a solucionarlo \ud83d\ude09<\/p>\n<h2>C\u00f3mo compartir historias en Instagram<\/h2>\n<p>Para compartir una historia en la que hayas sido mencionado, hay que seguir este proceso.<\/p>\n<p>1 &#8211; En una story, utiliza el sticker de menci\u00f3n o directamente escribe \u00ab@tunombre\u00bb. Aparecer\u00e1n varias sugerencias, en las que tendr\u00e1s que escoger el perfil que quieres.<\/p>\n<p>2 &#8211; Publ\u00edcala en \u00abTu historia\u00bb.<\/p>\n<p>3 &#8211; En los mensajes directos de la persona mencionada les notificar\u00e1 que han sido mencionados.<\/p>\n<p>4 &#8211; \u00a1En ese MD tendr\u00e1 disponible la opci\u00f3n de compartir en su historia!<\/p>\n<p>\u00bfAs\u00ed de f\u00e1cil? No del todo, porque no siempre aparece entre tus mensajes, o no es posible compartirla. Vamos a ver otras soluciones.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-5307 size-large\" src=\"https:\/\/socialpubli.com\/news\/wp-content\/uploads\/2019\/01\/como-compartir-historias-1024x853.png\" alt=\"\" width=\"1024\" height=\"853\" srcset=\"https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2019\/01\/como-compartir-historias-1024x853.png 1024w, https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2019\/01\/como-compartir-historias-200x167.png 200w, https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2019\/01\/como-compartir-historias-300x250.png 300w, https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2019\/01\/como-compartir-historias-768x640.png 768w, https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2019\/01\/como-compartir-historias-860x717.png 860w, https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2019\/01\/como-compartir-historias-680x567.png 680w, https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2019\/01\/como-compartir-historias-400x333.png 400w, https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2019\/01\/como-compartir-historias-50x42.png 50w, https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2019\/01\/como-compartir-historias.png 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h2>Activar \u00abPermitir compartir\u00bb en Instagram<\/h2>\n<p>El motivo m\u00e1s t\u00edpico es que la persona que publique la historia original no haya permitido compartir a sus seguidores.<\/p>\n<p>Para marcarlo, hay que ir a tu perfil -&gt; Configuraci\u00f3n -&gt; Privacidad y seguridad -&gt; Controles de historias -&gt; Contenido compartido.<\/p>\n<p>All\u00ed tienes varias opciones:<\/p>\n<ul>\n<li>Ocultar tus historias a contactos<\/li>\n<li>Elegir tu lista de mejores amigos para mostrarles stories solo a ellos.<\/li>\n<li>Elegir qui\u00e9n puede responder tus historias (para influencers top)<\/li>\n<li>Guardar en el archivo o galer\u00eda las publicaciones.<\/li>\n<li>Contenido compartido.<\/li>\n<\/ul>\n<p>En esta \u00faltima es donde tienes que marcar la casilla para que se quede en azul. Es decir, que tus contactos puedan compartir tus stories si los mencionas.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-5305 size-large\" src=\"https:\/\/socialpubli.com\/news\/wp-content\/uploads\/2019\/01\/permitir-compartir-instagram-1024x853.png\" alt=\"\" width=\"1024\" height=\"853\" srcset=\"https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2019\/01\/permitir-compartir-instagram-1024x853.png 1024w, https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2019\/01\/permitir-compartir-instagram-200x167.png 200w, https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2019\/01\/permitir-compartir-instagram-300x250.png 300w, https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2019\/01\/permitir-compartir-instagram-768x640.png 768w, https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2019\/01\/permitir-compartir-instagram-860x717.png 860w, https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2019\/01\/permitir-compartir-instagram-680x567.png 680w, https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2019\/01\/permitir-compartir-instagram-400x333.png 400w, https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2019\/01\/permitir-compartir-instagram-50x42.png 50w, https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2019\/01\/permitir-compartir-instagram.png 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h2>Otras razones por las que no puedes compartir historias de Instagram<\/h2>\n<h3>Cuenta privada en Instagram<\/h3>\n<p>Aunque hayan permitido compartir en su configuraci\u00f3n, no es posible recompartir historias de usuarios con cuenta privada.<\/p>\n<h3>No sois seguidores mutuos en Instagram<\/h3>\n<p>Puede que la menci\u00f3n haya llegado a la bandeja de entrada, pero est\u00e9 en el panel de solicitud de mensajes.<\/p>\n<h3>La historia de Instagram ha expirado<\/h3>\n<p>Tambi\u00e9n es posible que la story no se pueda compartir&#8230; porque ya han pasado 24 horas y ha desaparecido.<\/p>\n<h3>Te has equivocado al mencionar al usuario de Instagram<\/h3>\n<p>Aseg\u00farate de que todo est\u00e1 bien escrito y de que has elegido el perfil correcto mientras hac\u00edas la menci\u00f3n. Es posible que si no ten\u00edas conexi\u00f3n a internet en el momento de la publicaci\u00f3n, los perfiles no se hayan cargado correctamente.<\/p>\n<h3>La aplicaci\u00f3n de Instagram no est\u00e1 actualizada<\/h3>\n<p>No es una causa com\u00fan, pero alguna vez ha pasado que la aplicaci\u00f3n no estaba actualizada, o que incluso el modelo de smartphone no lo permita.<\/p>\n<p>A pesar de seguir estos pasos, hemos preguntado a varios influencers y algunos de ellos siguen sin poder compartir historias en las que han sido mencionados, mientras que otros mencionados en esa misma publicaci\u00f3n s\u00ed que han podido.<\/p>\n<p>Es algo que sucede a veces, y no encontramos la causa a pesar de todas las pruebas que hemos hecho.<\/p>\n<p>\u00a1Esperamos que Instagram lo solucione muy pronto!<\/p>\n<p>&nbsp;<\/p>\n<h6>Fotograf\u00eda de entrada por hannahkrajewski<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>\u00abNo puedo compartir stories\u00bb. Es una de las frases m\u00e1s tr\u00e1gicas de este a\u00f1o, y acecha a grupos de amigos de todo el mundo. Pero no hay que preocuparse, porque con este post vamos a solucionarlo \ud83d\ude09 C\u00f3mo compartir historias en Instagram Para compartir una historia en la que hayas sido mencionado, hay que seguir [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5303,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[40,48,291],"class_list":["post-5281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-redes-sociales","tag-consejos-instagram","tag-instagram","tag-stories"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfPor qu\u00e9 no puedo compartir historias de Instagram? | Social Publi Blog<\/title>\n<meta name=\"description\" content=\"&quot;No puedo compartir stories&quot;. Es una de las frases m\u00e1s tr\u00e1gicas de este a\u00f1o, y acecha a grupos de amigos de todo el mundo. Pero no hay que preocuparse, Si no puedes compartir stories en Instagram, te contamos por qu\u00e9 no es posible y c\u00f3mo solucionarlo. \u00a1Empieza a compartir historias en las que te mencionan!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/socialpubli.com\/blog\/es\/por-que-no-puedo-compartir-historias-instagram\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPor qu\u00e9 no puedo compartir historias de Instagram? | Social Publi Blog\" \/>\n<meta property=\"og:description\" content=\"&quot;No puedo compartir stories&quot;. Es una de las frases m\u00e1s tr\u00e1gicas de este a\u00f1o, y acecha a grupos de amigos de todo el mundo. Pero no hay que preocuparse, Si no puedes compartir stories en Instagram, te contamos por qu\u00e9 no es posible y c\u00f3mo solucionarlo. \u00a1Empieza a compartir historias en las que te mencionan!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/socialpubli.com\/blog\/es\/por-que-no-puedo-compartir-historias-instagram\/\" \/>\n<meta property=\"og:site_name\" content=\"Social Publi Blog\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-22T08:16:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2019\/01\/compartir-historias-instagram.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/por-que-no-puedo-compartir-historias-instagram\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/por-que-no-puedo-compartir-historias-instagram\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/#\\\/schema\\\/person\\\/26d7b037bc6b8f6a7086b73d14ce5d63\"},\"headline\":\"\u00bfPor qu\u00e9 no puedo compartir historias de Instagram?\",\"datePublished\":\"2019-01-22T08:16:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/por-que-no-puedo-compartir-historias-instagram\\\/\"},\"wordCount\":529,\"commentCount\":8,\"publisher\":{\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/por-que-no-puedo-compartir-historias-instagram\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/compartir-historias-instagram.jpg\",\"keywords\":[\"Consejos Instagram\",\"Instagram\",\"stories\"],\"articleSection\":[\"Redes Sociales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/por-que-no-puedo-compartir-historias-instagram\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/por-que-no-puedo-compartir-historias-instagram\\\/\",\"url\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/por-que-no-puedo-compartir-historias-instagram\\\/\",\"name\":\"\u00bfPor qu\u00e9 no puedo compartir historias de Instagram? | Social Publi Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/por-que-no-puedo-compartir-historias-instagram\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/por-que-no-puedo-compartir-historias-instagram\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/compartir-historias-instagram.jpg\",\"datePublished\":\"2019-01-22T08:16:14+00:00\",\"description\":\"\\\"No puedo compartir stories\\\". Es una de las frases m\u00e1s tr\u00e1gicas de este a\u00f1o, y acecha a grupos de amigos de todo el mundo. Pero no hay que preocuparse, Si no puedes compartir stories en Instagram, te contamos por qu\u00e9 no es posible y c\u00f3mo solucionarlo. \u00a1Empieza a compartir historias en las que te mencionan!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/por-que-no-puedo-compartir-historias-instagram\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/por-que-no-puedo-compartir-historias-instagram\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/por-que-no-puedo-compartir-historias-instagram\\\/#primaryimage\",\"url\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/compartir-historias-instagram.jpg\",\"contentUrl\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/compartir-historias-instagram.jpg\",\"width\":750,\"height\":500,\"caption\":\"compartir historias instagram\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/por-que-no-puedo-compartir-historias-instagram\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfPor qu\u00e9 no puedo compartir historias de Instagram?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/\",\"name\":\"Social Publi Blog\",\"description\":\"Tendencias en marketing de influencers, branded content y estrategia en redes sociales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/#organization\",\"name\":\"SocialPubli\",\"url\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/logo-blog.png\",\"contentUrl\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/logo-blog.png\",\"width\":284,\"height\":53,\"caption\":\"SocialPubli\"},\"image\":{\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/#\\\/schema\\\/person\\\/26d7b037bc6b8f6a7086b73d14ce5d63\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8eea57b285bdc2d2ad728ea4041506a69ae8e302228a422a8ef819d284c07da2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8eea57b285bdc2d2ad728ea4041506a69ae8e302228a422a8ef819d284c07da2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8eea57b285bdc2d2ad728ea4041506a69ae8e302228a422a8ef819d284c07da2?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n\"},\"url\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPor qu\u00e9 no puedo compartir historias de Instagram? | Social Publi Blog","description":"\"No puedo compartir stories\". Es una de las frases m\u00e1s tr\u00e1gicas de este a\u00f1o, y acecha a grupos de amigos de todo el mundo. Pero no hay que preocuparse, Si no puedes compartir stories en Instagram, te contamos por qu\u00e9 no es posible y c\u00f3mo solucionarlo. \u00a1Empieza a compartir historias en las que te mencionan!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/socialpubli.com\/blog\/es\/por-que-no-puedo-compartir-historias-instagram\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPor qu\u00e9 no puedo compartir historias de Instagram? | Social Publi Blog","og_description":"\"No puedo compartir stories\". Es una de las frases m\u00e1s tr\u00e1gicas de este a\u00f1o, y acecha a grupos de amigos de todo el mundo. Pero no hay que preocuparse, Si no puedes compartir stories en Instagram, te contamos por qu\u00e9 no es posible y c\u00f3mo solucionarlo. \u00a1Empieza a compartir historias en las que te mencionan!","og_url":"https:\/\/socialpubli.com\/blog\/es\/por-que-no-puedo-compartir-historias-instagram\/","og_site_name":"Social Publi Blog","article_published_time":"2019-01-22T08:16:14+00:00","og_image":[{"width":750,"height":500,"url":"https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2019\/01\/compartir-historias-instagram.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/socialpubli.com\/blog\/es\/por-que-no-puedo-compartir-historias-instagram\/#article","isPartOf":{"@id":"https:\/\/socialpubli.com\/blog\/es\/por-que-no-puedo-compartir-historias-instagram\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/socialpubli.com\/blog\/#\/schema\/person\/26d7b037bc6b8f6a7086b73d14ce5d63"},"headline":"\u00bfPor qu\u00e9 no puedo compartir historias de Instagram?","datePublished":"2019-01-22T08:16:14+00:00","mainEntityOfPage":{"@id":"https:\/\/socialpubli.com\/blog\/es\/por-que-no-puedo-compartir-historias-instagram\/"},"wordCount":529,"commentCount":8,"publisher":{"@id":"https:\/\/socialpubli.com\/blog\/#organization"},"image":{"@id":"https:\/\/socialpubli.com\/blog\/es\/por-que-no-puedo-compartir-historias-instagram\/#primaryimage"},"thumbnailUrl":"https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2019\/01\/compartir-historias-instagram.jpg","keywords":["Consejos Instagram","Instagram","stories"],"articleSection":["Redes Sociales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/socialpubli.com\/blog\/es\/por-que-no-puedo-compartir-historias-instagram\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/socialpubli.com\/blog\/es\/por-que-no-puedo-compartir-historias-instagram\/","url":"https:\/\/socialpubli.com\/blog\/es\/por-que-no-puedo-compartir-historias-instagram\/","name":"\u00bfPor qu\u00e9 no puedo compartir historias de Instagram? | Social Publi Blog","isPartOf":{"@id":"https:\/\/socialpubli.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/socialpubli.com\/blog\/es\/por-que-no-puedo-compartir-historias-instagram\/#primaryimage"},"image":{"@id":"https:\/\/socialpubli.com\/blog\/es\/por-que-no-puedo-compartir-historias-instagram\/#primaryimage"},"thumbnailUrl":"https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2019\/01\/compartir-historias-instagram.jpg","datePublished":"2019-01-22T08:16:14+00:00","description":"\"No puedo compartir stories\". Es una de las frases m\u00e1s tr\u00e1gicas de este a\u00f1o, y acecha a grupos de amigos de todo el mundo. Pero no hay que preocuparse, Si no puedes compartir stories en Instagram, te contamos por qu\u00e9 no es posible y c\u00f3mo solucionarlo. \u00a1Empieza a compartir historias en las que te mencionan!","breadcrumb":{"@id":"https:\/\/socialpubli.com\/blog\/es\/por-que-no-puedo-compartir-historias-instagram\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/socialpubli.com\/blog\/es\/por-que-no-puedo-compartir-historias-instagram\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/socialpubli.com\/blog\/es\/por-que-no-puedo-compartir-historias-instagram\/#primaryimage","url":"https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2019\/01\/compartir-historias-instagram.jpg","contentUrl":"https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2019\/01\/compartir-historias-instagram.jpg","width":750,"height":500,"caption":"compartir historias instagram"},{"@type":"BreadcrumbList","@id":"https:\/\/socialpubli.com\/blog\/es\/por-que-no-puedo-compartir-historias-instagram\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/socialpubli.com\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00bfPor qu\u00e9 no puedo compartir historias de Instagram?"}]},{"@type":"WebSite","@id":"https:\/\/socialpubli.com\/blog\/#website","url":"https:\/\/socialpubli.com\/blog\/","name":"Social Publi Blog","description":"Tendencias en marketing de influencers, branded content y estrategia en redes sociales.","publisher":{"@id":"https:\/\/socialpubli.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/socialpubli.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/socialpubli.com\/blog\/#organization","name":"SocialPubli","url":"https:\/\/socialpubli.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/socialpubli.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2017\/01\/logo-blog.png","contentUrl":"https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2017\/01\/logo-blog.png","width":284,"height":53,"caption":"SocialPubli"},"image":{"@id":"https:\/\/socialpubli.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/socialpubli.com\/blog\/#\/schema\/person\/26d7b037bc6b8f6a7086b73d14ce5d63","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8eea57b285bdc2d2ad728ea4041506a69ae8e302228a422a8ef819d284c07da2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8eea57b285bdc2d2ad728ea4041506a69ae8e302228a422a8ef819d284c07da2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8eea57b285bdc2d2ad728ea4041506a69ae8e302228a422a8ef819d284c07da2?s=96&d=mm&r=g","caption":"Redacci\u00f3n"},"url":"https:\/\/socialpubli.com\/blog\/es\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/socialpubli.com\/blog\/es\/wp-json\/wp\/v2\/posts\/5281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/socialpubli.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/socialpubli.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/socialpubli.com\/blog\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/socialpubli.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=5281"}],"version-history":[{"count":5,"href":"https:\/\/socialpubli.com\/blog\/es\/wp-json\/wp\/v2\/posts\/5281\/revisions"}],"predecessor-version":[{"id":5314,"href":"https:\/\/socialpubli.com\/blog\/es\/wp-json\/wp\/v2\/posts\/5281\/revisions\/5314"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/socialpubli.com\/blog\/es\/wp-json\/wp\/v2\/media\/5303"}],"wp:attachment":[{"href":"https:\/\/socialpubli.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=5281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/socialpubli.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=5281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/socialpubli.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=5281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}