{"id":623,"date":"2015-08-05T10:14:48","date_gmt":"2015-08-05T08:14:48","guid":{"rendered":"https:\/\/socialpubli.com\/news\/?p=623"},"modified":"2025-09-15T14:13:42","modified_gmt":"2025-09-15T12:13:42","slug":"facebook-mejora-sus-videos-para-plantarle-cara-a-youtube","status":"publish","type":"post","link":"https:\/\/socialpubli.com\/blog\/es\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\/","title":{"rendered":"Facebook mejora sus v\u00eddeos para plantarle cara a Youtube"},"content":{"rendered":"<p>Seguro que m\u00e1s de una vez has escuchado eso de que el v\u00eddeo se est\u00e1 convirtiendo en el tipo de contenido favorito de los internautas (y por lo tanto, de marcas y anunciantes). Es m\u00e1s, no ser\u00eda de extra\u00f1ar que tambi\u00e9n fuese tu tipo de contenido favorito.<\/p>\n<p>Como no pod\u00eda ser de otra forma, <a href=\"https:\/\/es-es.facebook.com\/\" target=\"_blank\">Facebook<\/a> tambi\u00e9n lo sabe.<\/p>\n<p>El v\u00eddeo tiene un alto potencial de <strong>viralidad<\/strong>, genera una <strong>gran cantidad de interacciones<\/strong> y, en consecuencia, <strong>fomenta la implicaci\u00f3n de los usuarios<\/strong>. Probablemente por esa raz\u00f3n, uno de los objetivos de la empresa de Mark Zuckerberg es ganarle terreno al l\u00edder indiscutible de este sector: <a href=\"https:\/\/www.youtube.com\/\" target=\"_blank\">Youtube<\/a>.<\/p>\n<p>Primero llegaron los <strong>\u201cautoplay\u201d<\/strong> o reproducciones autom\u00e1ticas. Ahora llegan una serie de funciones que se igualan (e incluso mejoran en algunos aspectos) a las que ofrece la filial de Google.<\/p>\n<p>Una de las novedades m\u00e1s destacadas es la opci\u00f3n de <strong>elegir p\u00fablicos muy segmentados. <\/strong> Aprovechando el ingente volumen de datos personales que amablemente le proporcionamos a Facebook cada d\u00eda, se podr\u00e1 elegir con una mayor exactitud qui\u00e9n puede ver los v\u00eddeos que subimos. \u00bfSolo mujeres? \u00bfSolo ni\u00f1os? \u00bfSolo adultos? \u00bfSolo gente que hable un idioma determinado? Sin lugar a dudas esta capacidad de elecci\u00f3n abre un buen abanico de posibilidades para los anunciantes que apuestan por el contenido audiovisual en internet.<\/p>\n<p>Otra de las funcionalidades que se han incluido es la de <strong>publicar v\u00eddeos sin listar<\/strong>. Es decir, v\u00eddeos privados que no aparecen en la cronolog\u00eda y a los que solo podemos acceder si quien los ha subido nos proporciona su URL directa. As\u00ed, podremos seleccionar uno a uno qui\u00e9nes van a visualizarlo.<\/p>\n<p>Adem\u00e1s, se han a\u00f1adido nuevas opciones de personalizaci\u00f3n como la posibilidad de <strong>elegir la imagen previa o \u201cthumbnail\u201d,\u00a0<\/strong> que representa al v\u00eddeo cuando no se est\u00e1 reproduciendo, el poder <strong>modificar la fecha de publicaci\u00f3n<\/strong> o <strong>restringir la inserci\u00f3n<\/strong> en p\u00e1ginas webs ajenas.<\/p>\n<p>Con esta bater\u00eda de actualizaciones, Facebook quiere que los <strong>Community Managers<\/strong> de las marcas tengan en cuenta su servicio a la hora de planear estrategias con v\u00eddeo en la red. Pretenden posicionarse como <strong>una alternativa s\u00f3lida y real<\/strong> al gigante de Youtube, que lleva ya diez a\u00f1os liderando el sector con una gran holgura y que mueve cifras millonarias en concepto de publicidad.<\/p>\n<p>\u00bfCrees que lograr\u00e1n plantarle cara?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seguro que m\u00e1s de una vez has escuchado eso de que el v\u00eddeo se est\u00e1 convirtiendo en el tipo de contenido favorito de los internautas (y por lo tanto, de marcas y anunciantes). Es m\u00e1s, no ser\u00eda de extra\u00f1ar que tambi\u00e9n fuese tu tipo de contenido favorito. Como no pod\u00eda ser de otra forma, Facebook [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":624,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[85,29,83,84],"class_list":["post-623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-redes-sociales","tag-app","tag-facebook","tag-noticias","tag-videos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Facebook mejora sus v\u00eddeos y compite con Youtube | SocialPubli Blog<\/title>\n<meta name=\"description\" content=\"Facebook da un paso m\u00e1s mejorando su oferta de v\u00eddeos. \u00bfSe ha vuelto competencia directa de YouTube? \u00a1Te lo contamos todo en nuestro art\u00edculo!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/socialpubli.com\/blog\/es\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Facebook mejora sus v\u00eddeos y compite con Youtube | SocialPubli Blog\" \/>\n<meta property=\"og:description\" content=\"Facebook da un paso m\u00e1s mejorando su oferta de v\u00eddeos. \u00bfSe ha vuelto competencia directa de YouTube? \u00a1Te lo contamos todo en nuestro art\u00edculo!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/socialpubli.com\/blog\/es\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\/\" \/>\n<meta property=\"og:site_name\" content=\"Social Publi Blog\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-05T08:14:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-15T12:13:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2015\/08\/FBvideos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"641\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/#\\\/schema\\\/person\\\/26d7b037bc6b8f6a7086b73d14ce5d63\"},\"headline\":\"Facebook mejora sus v\u00eddeos para plantarle cara a Youtube\",\"datePublished\":\"2015-08-05T08:14:48+00:00\",\"dateModified\":\"2025-09-15T12:13:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\\\/\"},\"wordCount\":425,\"publisher\":{\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/FBvideos.jpg\",\"keywords\":[\"app\",\"facebook\",\"noticias\",\"v\u00eddeos\"],\"articleSection\":[\"Redes Sociales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\\\/\",\"url\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\\\/\",\"name\":\"Facebook mejora sus v\u00eddeos y compite con Youtube | SocialPubli Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/FBvideos.jpg\",\"datePublished\":\"2015-08-05T08:14:48+00:00\",\"dateModified\":\"2025-09-15T12:13:42+00:00\",\"description\":\"Facebook da un paso m\u00e1s mejorando su oferta de v\u00eddeos. \u00bfSe ha vuelto competencia directa de YouTube? \u00a1Te lo contamos todo en nuestro art\u00edculo!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\\\/#primaryimage\",\"url\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/FBvideos.jpg\",\"contentUrl\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/FBvideos.jpg\",\"width\":1600,\"height\":641},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Facebook mejora sus v\u00eddeos para plantarle cara a Youtube\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/\",\"name\":\"Social Publi Blog\",\"description\":\"Tendencias en marketing de influencers, branded content y estrategia en redes sociales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/#organization\",\"name\":\"SocialPubli\",\"url\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/logo-blog.png\",\"contentUrl\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/logo-blog.png\",\"width\":284,\"height\":53,\"caption\":\"SocialPubli\"},\"image\":{\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/#\\\/schema\\\/person\\\/26d7b037bc6b8f6a7086b73d14ce5d63\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8eea57b285bdc2d2ad728ea4041506a69ae8e302228a422a8ef819d284c07da2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8eea57b285bdc2d2ad728ea4041506a69ae8e302228a422a8ef819d284c07da2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8eea57b285bdc2d2ad728ea4041506a69ae8e302228a422a8ef819d284c07da2?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n\"},\"url\":\"https:\\\/\\\/socialpubli.com\\\/blog\\\/es\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Facebook mejora sus v\u00eddeos y compite con Youtube | SocialPubli Blog","description":"Facebook da un paso m\u00e1s mejorando su oferta de v\u00eddeos. \u00bfSe ha vuelto competencia directa de YouTube? \u00a1Te lo contamos todo en nuestro art\u00edculo!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/socialpubli.com\/blog\/es\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\/","og_locale":"es_ES","og_type":"article","og_title":"Facebook mejora sus v\u00eddeos y compite con Youtube | SocialPubli Blog","og_description":"Facebook da un paso m\u00e1s mejorando su oferta de v\u00eddeos. \u00bfSe ha vuelto competencia directa de YouTube? \u00a1Te lo contamos todo en nuestro art\u00edculo!","og_url":"https:\/\/socialpubli.com\/blog\/es\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\/","og_site_name":"Social Publi Blog","article_published_time":"2015-08-05T08:14:48+00:00","article_modified_time":"2025-09-15T12:13:42+00:00","og_image":[{"width":1600,"height":641,"url":"https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2015\/08\/FBvideos.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/socialpubli.com\/blog\/es\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\/#article","isPartOf":{"@id":"https:\/\/socialpubli.com\/blog\/es\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/socialpubli.com\/blog\/#\/schema\/person\/26d7b037bc6b8f6a7086b73d14ce5d63"},"headline":"Facebook mejora sus v\u00eddeos para plantarle cara a Youtube","datePublished":"2015-08-05T08:14:48+00:00","dateModified":"2025-09-15T12:13:42+00:00","mainEntityOfPage":{"@id":"https:\/\/socialpubli.com\/blog\/es\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\/"},"wordCount":425,"publisher":{"@id":"https:\/\/socialpubli.com\/blog\/#organization"},"image":{"@id":"https:\/\/socialpubli.com\/blog\/es\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\/#primaryimage"},"thumbnailUrl":"https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2015\/08\/FBvideos.jpg","keywords":["app","facebook","noticias","v\u00eddeos"],"articleSection":["Redes Sociales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/socialpubli.com\/blog\/es\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\/","url":"https:\/\/socialpubli.com\/blog\/es\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\/","name":"Facebook mejora sus v\u00eddeos y compite con Youtube | SocialPubli Blog","isPartOf":{"@id":"https:\/\/socialpubli.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/socialpubli.com\/blog\/es\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\/#primaryimage"},"image":{"@id":"https:\/\/socialpubli.com\/blog\/es\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\/#primaryimage"},"thumbnailUrl":"https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2015\/08\/FBvideos.jpg","datePublished":"2015-08-05T08:14:48+00:00","dateModified":"2025-09-15T12:13:42+00:00","description":"Facebook da un paso m\u00e1s mejorando su oferta de v\u00eddeos. \u00bfSe ha vuelto competencia directa de YouTube? \u00a1Te lo contamos todo en nuestro art\u00edculo!","breadcrumb":{"@id":"https:\/\/socialpubli.com\/blog\/es\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/socialpubli.com\/blog\/es\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/socialpubli.com\/blog\/es\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\/#primaryimage","url":"https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2015\/08\/FBvideos.jpg","contentUrl":"https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2015\/08\/FBvideos.jpg","width":1600,"height":641},{"@type":"BreadcrumbList","@id":"https:\/\/socialpubli.com\/blog\/es\/facebook-mejora-sus-videos-para-plantarle-cara-a-youtube\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/socialpubli.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Facebook mejora sus v\u00eddeos para plantarle cara a Youtube"}]},{"@type":"WebSite","@id":"https:\/\/socialpubli.com\/blog\/#website","url":"https:\/\/socialpubli.com\/blog\/","name":"Social Publi Blog","description":"Tendencias en marketing de influencers, branded content y estrategia en redes sociales.","publisher":{"@id":"https:\/\/socialpubli.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/socialpubli.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/socialpubli.com\/blog\/#organization","name":"SocialPubli","url":"https:\/\/socialpubli.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/socialpubli.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2017\/01\/logo-blog.png","contentUrl":"https:\/\/socialpubli.com\/blog\/wp-content\/uploads\/2017\/01\/logo-blog.png","width":284,"height":53,"caption":"SocialPubli"},"image":{"@id":"https:\/\/socialpubli.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/socialpubli.com\/blog\/#\/schema\/person\/26d7b037bc6b8f6a7086b73d14ce5d63","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8eea57b285bdc2d2ad728ea4041506a69ae8e302228a422a8ef819d284c07da2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8eea57b285bdc2d2ad728ea4041506a69ae8e302228a422a8ef819d284c07da2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8eea57b285bdc2d2ad728ea4041506a69ae8e302228a422a8ef819d284c07da2?s=96&d=mm&r=g","caption":"Redacci\u00f3n"},"url":"https:\/\/socialpubli.com\/blog\/es\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/socialpubli.com\/blog\/es\/wp-json\/wp\/v2\/posts\/623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/socialpubli.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/socialpubli.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/socialpubli.com\/blog\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/socialpubli.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=623"}],"version-history":[{"count":3,"href":"https:\/\/socialpubli.com\/blog\/es\/wp-json\/wp\/v2\/posts\/623\/revisions"}],"predecessor-version":[{"id":627,"href":"https:\/\/socialpubli.com\/blog\/es\/wp-json\/wp\/v2\/posts\/623\/revisions\/627"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/socialpubli.com\/blog\/es\/wp-json\/wp\/v2\/media\/624"}],"wp:attachment":[{"href":"https:\/\/socialpubli.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/socialpubli.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/socialpubli.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}